{"id":3790,"date":"2020-07-14T11:00:00","date_gmt":"2020-07-14T09:00:00","guid":{"rendered":"https:\/\/138.68.92.186\/?p=3790"},"modified":"2026-02-23T14:21:33","modified_gmt":"2026-02-23T13:21:33","slug":"etude-panne-gros-electromenager-chiffres-cles","status":"publish","type":"post","link":"https:\/\/www.adepem.com\/blog\/etude-panne-gros-electromenager-chiffres-cles\/","title":{"rendered":"\u00c9tude des pannes sur le gros \u00e9lectrom\u00e9nager : d\u00e9couvrez les chiffres cl\u00e9s !"},"content":{"rendered":"\n<ul class=\"wp-block-advgb-summary advgb-toc alignnone\"><li class=\"toc-level-1\"><a href=\"#1-appareil-electromenager-sur-2-qui-tombe-en-panne-a-moins-de-5-ans-0656710e-f8f3-4922-b7b5-f1182bd38ca9\">1 appareil \u00e9lectrom\u00e9nager sur 2 qui tombe en panne a moins de 5 ans<\/a><\/li><li class=\"toc-level-1\"><a href=\"#nature-des-pannes-les-plus-recurrentes-0dea5861-070a-4925-9bbc-a7f96e7e1651\">Nature des pannes les plus r\u00e9currentes<\/a><\/li><li class=\"toc-level-2\"><a href=\"#quel-conseil-pour-eviter-les-pannes-bien-entretenir-son-electromenager--16f1701e-bc53-458d-b1e3-19f8ab6aa858\">Quel conseil pour \u00e9viter les pannes ? Bien entretenir son \u00e9lectrom\u00e9nager !<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Machine \u00e0 laver (nos <a href=\"https:\/\/www.adepem.com\/a\/lave-linge\">pi\u00e8ces d\u00e9tach\u00e9es machine \u00e0 laver<\/a>) qui affiche un code d\u2019erreur, lave vaisselle qui refuse de vidanger son eau de lavage\u2026 nous avons tous \u00e9t\u00e9 confront\u00e9s, au moins une fois dans notre vie, \u00e0 une panne d\u2019appareils \u00e9lectriques. Murfy, la startup sp\u00e9cialis\u00e9e dans la r\u00e9paration d\u2019\u00e9lectrom\u00e9nager \u00e0 domicile, a justement men\u00e9 une enqu\u00eate sur le sujet dans le cadre de la Semaine Europ\u00e9enne du D\u00e9veloppement durable. D\u00e9couvrons ensemble les conclusions de l\u2019\u00e9tude dans notre article.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"1-appareil-electromenager-sur-2-qui-tombe-en-panne-a-moins-de-5-ans-0656710e-f8f3-4922-b7b5-f1182bd38ca9\">1 appareil \u00e9lectrom\u00e9nager sur 2 qui tombe en panne a moins de 5 ans<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019information capitale que nous r\u00e9v\u00e8le cette \u00e9tude* est que plus d\u2019un quart du gros appareil \u00e9lectrom\u00e9nager ne fonctionne plus dans les deux ann\u00e9es qui suivent la fin de sa garantie. <em>\u201cSi l\u2019analyse des donn\u00e9es collect\u00e9es confirme clairement les fortes disparit\u00e9s de dur\u00e9e de vie des appareils \u00e9lectrom\u00e9nagers en fonction de leur marque, un constat s\u2019impose pour tous : les pannes toucheront tous les consommateurs \u00e0 un moment ou l\u2019autre. Et alors que 80% des pannes du gros \u00e9lectrom\u00e9nager sont r\u00e9parables \u00e0 un prix raisonnable, la majorit\u00e9 des Fran\u00e7ais jette leurs appareils d\u00e9courag\u00e9s par les d\u00e9lais d\u2019intervention et les co\u00fbts des r\u00e9parations pratiqu\u00e9s par les grands distributeurs du secteur. Dans ce contexte, le projet de loi sur l\u2019\u00e9conomie circulaire qui pr\u00e9voit la mise en place d\u2019un indice de r\u00e9parabilit\u00e9 devrait redistribuer un peu les cartes <\/em>\u201c affirme Guy Pezaku, le CEO de Murfy. L\u2019entreprise a estim\u00e9 le nombre de cycles moyen avant la premi\u00e8re panne \u00e0 872.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nature-des-pannes-les-plus-recurrentes-0dea5861-070a-4925-9bbc-a7f96e7e1651\">Nature des pannes les plus r\u00e9currentes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019\u00e9tude a \u00e9galement analys\u00e9 les probl\u00e8mes majeurs rencontr\u00e9s sur le gros \u00e9lectrom\u00e9nager. En effet, il en ressort que toutes les cat\u00e9gories d\u2019appareils sont touch\u00e9s par le m\u00eame probl\u00e8me : la perte d\u2019efficacit\u00e9. Pour la machine \u00e0 laver il s\u2019agira d\u2019un v\u00eatement mal lav\u00e9, pour le lave vaisselle de couverts mal nettoy\u00e9s et pour le s\u00e8che linge, d\u2019un v\u00eatement mal s\u00e9ch\u00e9. Ce sont 1013 appareils qui sont vis\u00e9s par cette perte de performance. Les pannes le plus majoritairement identifi\u00e9es pour le lave-linge et le lave-vaisselle sont : le probl\u00e8me de vidange (1038 appareils) et le probl\u00e8me de d\u00e9marrage (1153 appareils).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"quel-conseil-pour-eviter-les-pannes-bien-entretenir-son-electromenager--16f1701e-bc53-458d-b1e3-19f8ab6aa858\">Quel conseil pour \u00e9viter les pannes ? Bien entretenir son \u00e9lectrom\u00e9nager !<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s avoir pass\u00e9 en revue tous les dysfonctionnements que pouvaient rencontrer les consommateurs avec leur \u00e9lectrom\u00e9nager, l\u2019\u00e9tude nous explique comment les \u00e9viter. Et la solution r\u00e9side dans l\u2019importance de l\u2019entretien qui est un gage de durabilit\u00e9. Pour que votre appareil soit aussi efficace qu&rsquo;\u00e0 ses premi\u00e8res heures d\u2019utilisation, il n\u2019y a pas de secret, il faut imp\u00e9rativement en prendre soin. Lorsqu\u2019on sait que sur les 28 millions d\u2019appareils qui sont sujet au panne, 60% d\u2019entre eux auraient pu \u00eatre sauv\u00e9s, on r\u00e9alise \u00e0 quel point un entretien minutieux peut faire toute la diff\u00e9rence. Un bon entretien vous garantira une plus longue dur\u00e9e de vie de vos \u00e9quipements et vous \u00e9vitera le gaspillage. Voici les 3 conseils donn\u00e9s dans l\u2019\u00e9tude \u00e0 mettre en pratique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nettoyer son \u00e9lectrom\u00e9nager (comme par exemple <a href=\"https:\/\/www.adepem.com\/blog\/nettoyer-machine-laver\/\">nettoyer son lave-linge<\/a>) de mani\u00e8re r\u00e9guli\u00e8re \u00e0 raison d\u2019une fois par mois (filtres et r\u00e9servoirs compris) vous permettra de vous assurer qu\u2019aucun \u00e9l\u00e9ment n\u2019obstrue votre appareil.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Faire fr\u00e9quemment un lavage \u00e0 vide \u00e0 une temp\u00e9rature de 75\/90\u00b0 luttera contre le d\u00e9p\u00f4t de calcaire et la pr\u00e9sence de bact\u00e9rie dans votre machine \u00e0 laver. Pensez \u00e0 ajouter du vinaigre blanc dans votre bac \u00e0 assouplissant pour un nettoyage optimal. Quand \u00e0 votre lave-vaisselle, assurez-vous qu\u2019il n\u2019est pas dot\u00e9 de joint, auquel cas il faudra \u00e9viter tout ajout de vinaigre.<\/li><li>Doser la lessive avec parcimonie en la diluant avec un peu d&rsquo;eau pour \u00e9viter qu\u2019elle ne colle dans le bac \u00e0 d\u00e9tergent. Eviter de surcharger sa machine et respecter le poid maximum de linge. Adopter des gestes \u00e9colos : les lingettes d\u00e9colorantes sont \u00e0 proscrire puisqu&rsquo;elles finissent souvent par boucher les pompes, les balles de lavages vous feront \u00e9conomiser de la lessive et enfin une temp\u00e9rature \u00e0 30\u00b0 vous fera d\u00e9penser moins d\u2019\u00e9nergie.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">*Il s\u2019agit d\u2019une \u00e9tude sur les pannes rencontr\u00e9es par les gros appareils \u00e9lectrom\u00e9nagers de type lave-linge, s\u00e8che-linge et lave-vaisselle (nos <a href=\"https:\/\/www.adepem.com\/a\/lave-vaisselle\">pi\u00e8ces d\u00e9tach\u00e9es lave-vaisselle<\/a>). Pour la r\u00e9aliser, l\u2019entreprise s\u2019est bas\u00e9e sur 6500 questionnaires remplis pendant la p\u00e9riode allant de septembre 2018 \u00e0 avril 2019, par des consommateurs fran\u00e7ais ayant rencontr\u00e9 ce type de dysfonctionnement. L\u2019\u00e9tude concerne tout type de marque : Miele, Siemens, Brandt, Whirlpool, Bosch, Indesit, Samsung, Candy, LG ou encore Proline.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Source : <a href=\"https:\/\/www.actu-environnement.com\/media\/pdf\/dit-aujourdhui\/823-etude.pdf\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener nofollow\" class=\"rank-math-link\">https:\/\/www.actu-environnement.com\/media\/pdf\/dit-aujourdhui\/823-etude.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Machine \u00e0 laver (nos pi\u00e8ces d\u00e9tach\u00e9es machine \u00e0 laver) qui affiche un code d\u2019erreur, lave vaisselle qui refuse de vidanger son eau de lavage\u2026 nous avons tous \u00e9t\u00e9 confront\u00e9s, au moins une fois dans notre vie, \u00e0 une panne d\u2019appareils \u00e9lectriques. Murfy, la startup sp\u00e9cialis\u00e9e dans la r\u00e9paration d\u2019\u00e9lectrom\u00e9nager \u00e0 domicile, a justement men\u00e9 une enqu\u00eate sur le sujet dans le cadre de la Semaine Europ\u00e9enne du D\u00e9veloppement durable. D\u00e9couvrons ensemble les conclusions de l\u2019\u00e9tude dans notre article. 1 appareil \u00e9lectrom\u00e9nager sur 2 qui tombe en panne a moins de 5 ans L\u2019information capitale que nous r\u00e9v\u00e8le cette \u00e9tude* est&hellip;<\/p>\n","protected":false},"author":5,"featured_media":3798,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[481],"tags":[],"class_list":["post-3790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-electromenager"],"modified_by":"Quentin","author_meta":{"display_name":"Fred","author_link":"https:\/\/www.adepem.com\/blog\/auteur\/fred\/"},"featured_img":"https:\/\/www.adepem.com\/blog\/wp-content\/uploads\/2020\/07\/etude-panne-gros-electromenager-chiffres-cles-270x180.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.adepem.com\/blog\/actu-electromenager\/\" class=\"advgb-post-tax-term\">L\u2019actu \u00e9lectrom\u00e9nager<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">L\u2019actu \u00e9lectrom\u00e9nager<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 6 ans il y a","modified":"Mis \u00e0 jour 6 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 14 juillet 2020","modified":"Mise \u00e0 jour le 23 f\u00e9vrier 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 14 juillet 2020 11 h 00 min","modified":"Mise \u00e0 jour le 23 f\u00e9vrier 2026 14 h 21 min"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts\/3790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/comments?post=3790"}],"version-history":[{"count":5,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts\/3790\/revisions"}],"predecessor-version":[{"id":7199,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts\/3790\/revisions\/7199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/media\/3798"}],"wp:attachment":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/media?parent=3790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/categories?post=3790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/tags?post=3790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}