{"id":4480,"date":"2021-03-05T07:00:00","date_gmt":"2021-03-05T06:00:00","guid":{"rendered":"https:\/\/138.68.92.186\/?p=4480"},"modified":"2021-03-02T17:19:44","modified_gmt":"2021-03-02T16:19:44","slug":"beko-refrigerateurs-technologie-harvestfresh","status":"publish","type":"post","link":"https:\/\/www.adepem.com\/blog\/beko-refrigerateurs-technologie-harvestfresh\/","title":{"rendered":"Beko innove sa gamme de r\u00e9frig\u00e9rateurs gr\u00e2ce \u00e0 la technologie HarvestFresh"},"content":{"rendered":"\n<ul class=\"wp-block-advgb-summary advgb-toc alignnone\"><li class=\"toc-level-1\" style=\"margin-left:20px\"><a href=\"#en-quoi-consiste-la-technologie-harvest-fresh--a3d215e7-cb42-4264-b31a-62feef199230\">En quoi consiste la technologie Harvest Fresh ?<\/a><\/li><li class=\"toc-level-2\" style=\"margin-left:40px\"><a href=\"#le-refrigerateur-rcna366i40zxbn-c8196091-3c1d-4b9a-a875-f7856b4ba8ec\">Le r\u00e9frig\u00e9rateur RCNA366I40ZXBN<\/a><\/li><li class=\"toc-level-2\" style=\"margin-left:40px\"><a href=\"#le-refrigerateur-rcne366e40zxbn-f558e62b-1611-4287-8ee6-0cd4e2edbe19\">Le r\u00e9frig\u00e9rateur RCNE366E40ZXBN<\/a><\/li><li class=\"toc-level-2\" style=\"margin-left:40px\"><a href=\"#le-refrigerateur-rcne560e40zxpn-3f66a4ed-206e-4f50-a2e8-bd7c9304d717\">Le r\u00e9frig\u00e9rateur RCNE560E40ZXPN<\/a><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Le fabricant Beko innove dans ses nouvelles gammes de r\u00e9frig\u00e9rateurs gr\u00e2ce \u00e0 la <strong>technologie HarvestFresh<\/strong> inspir\u00e9e par la nature. On vous explique tout.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a class=\"rank-math-link\" href=\"https:\/\/www.adepem.com\/m\/beko\">Beko<\/a> est une des entreprises europ\u00e9ennes leaders dans l&rsquo;\u00e9lectrom\u00e9nager appartenant au groupe turc Ar\u00e7elike. Le fabricant vient de sortir sa nouvelle gamme de r\u00e9frig\u00e9rateurs en int\u00e9grant le syst\u00e8me HarvestFresh. <strong>Le HarvestFresh est une technologie inspir\u00e9e par la nature, permettant de simuler les changements de lumi\u00e8re dans votre r\u00e9frig\u00e9rateur tout au long de la journ\u00e9e<\/strong>. Cette technique a pour objectif d\u2019am\u00e9liorer la conservation des aliments. Ces nouveaux r\u00e9frig\u00e9rateurs sont compos\u00e9s d\u2019un ensemble de leds (bleues, vertes et rouges) qui reproduisent le cycle du soleil dans le bac \u00e0 l\u00e9gumes afin de pr\u00e9server les vitamines plus longtemps. <strong>Les leds changent de couleur et d&rsquo;intensit\u00e9, selon l\u2019heure de la journ\u00e9e afin mieux conserver les fruits et l\u00e9gumes<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"en-quoi-consiste-la-technologie-harvest-fresh--a3d215e7-cb42-4264-b31a-62feef199230\">En quoi consiste la technologie Harvest Fresh ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Beko avait pr\u00e9sent\u00e9 sa nouvelle technologie Harvest Fresh lors du r\u00e9cent salon IFA 2019, qui a eu lieu \u00e0 Berlin en septembre, et o\u00f9 les constructeurs se rendent pour pr\u00e9senter leurs nouveaux produits\u2026 et surtout les <a class=\"rank-math-link\" href=\"https:\/\/www.adepem.com\/blog\/electromenager-innovations-lave-vaisselle-refrigerateur-four-lave-linge\/\">innovations de demain<\/a>. La marque d\u2019\u00e9lectrom\u00e9nager avait fait la d\u00e9monstration de sa nouvelle technologie : <strong>les leds int\u00e9gr\u00e9s dans le r\u00e9frig\u00e9rateur fonctionnent en photosynth\u00e8se en se rythmant sur la journ\u00e9e<\/strong> en commen\u00e7ant par la lumi\u00e8re bleue qui d\u00e9bute le processus, puis pas une lumi\u00e8re verte \u00e0 midi et enfin une lumi\u00e8re rouge en fin de journ\u00e9e jusqu&rsquo;\u00e0 la nuit, durant laquelle les lumi\u00e8res Leds du r\u00e9frig\u00e9rateur sont totalement mises en veille.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019objectif de l\u2019int\u00e9gration du syst\u00e8me HarvestFresh dans certains mod\u00e8les de r\u00e9frig\u00e9rateur n&rsquo;est pas de conserver le plus longtemps possible les aliments, mais de leur permettre de <strong>pr\u00e9server au maximum leur qualit\u00e9 nutritionnelle<\/strong> tout particuli\u00e8rement les vitamines A et C. En effet, les l\u00e9gumes et fruits compos\u00e9s de vitamines A et C sont tr\u00e8s sensibles au manque de lumi\u00e8re qui d\u00e9t\u00e9riore peu \u00e0 peu les teneurs en vitamine.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le directeur marketing de Beko, Zeynep Yalim Uzun, a pr\u00e9cis\u00e9 lors d\u2019une interview que l\u2019entreprise a pour ambition de perfectionner la technologie de leurs appareils afin d&rsquo;am\u00e9liorer le bien-\u00eatre, autour d\u2019une alimentation de plus en plus saine, en conservant le plus longtemps possible leurs b\u00e9n\u00e9fices.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les mod\u00e8les de r\u00e9frig\u00e9rateurs \u00e9quip\u00e9s sur syst\u00e8me HarvestFresh pr\u00e9servent les propri\u00e9t\u00e9s des aliments et des nutriments mais conservent \u00e9galement la m\u00eame fra\u00eecheur que les r\u00e9frig\u00e9rateurs classiques. <strong>Le syst\u00e8me HarvestFresh a m\u00eame \u00e9t\u00e9 test\u00e9 et valid\u00e9 par un <\/strong><strong>Test Intertek&nbsp; (laboratoire ind\u00e9pendant)<\/strong> qui se base sur la mesure de vitamines C et A (b\u00eata-carot\u00e8ne) dans les tomates et poivrons verts durant une p\u00e9riode de 7 jours. Le fabricant Beko a d\u00e9j\u00e0 mis sur le march\u00e9 de l&rsquo;\u00e9lectrom\u00e9nager trois nouveaux mod\u00e8les poss\u00e9dant la technologie HarvestFresh.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"le-refrigerateur-rcna366i40zxbn-c8196091-3c1d-4b9a-a875-f7856b4ba8ec\">Le r\u00e9frig\u00e9rateur RCNA366I40ZXBN<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ce mod\u00e8le de r\u00e9frig\u00e9rateur est dot\u00e9 d\u2019un volume total de 324 Litres dont 215 L pour la partie r\u00e9frig\u00e9ration et 109 L pour la partie cong\u00e9lation, dont chacun des compartiments est dot\u00e9 <strong>d&rsquo;un froid ventil\u00e9 et d\u2019un froid No Frost<\/strong>. Ce r\u00e9frig\u00e9rateur poss\u00e8de \u00e9galement <strong>un bac \u00e0 l\u00e9gumes HarvestFresh<\/strong> permettant de maintenir la temp\u00e9rature des produits juste au-dessus de 0 degr\u00e9, pour une meilleure conservation des aliments fragiles et sensibles. Les panneaux de commande de r\u00e9glage des temp\u00e9ratures \u00e9lectroniques du r\u00e9frig\u00e9rateur se trouvent derri\u00e8re la porte de l\u2019appareil. <strong>Son prix est de 699 euros.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"le-refrigerateur-rcne366e40zxbn-f558e62b-1611-4287-8ee6-0cd4e2edbe19\">Le r\u00e9frig\u00e9rateur RCNE366E40ZXBN<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le <\/strong><strong>r\u00e9frig\u00e9rateur <\/strong><strong>RCNE366E40ZXBN poss\u00e8de la m\u00eame capacit\u00e9 que le <\/strong><strong>r\u00e9frig\u00e9rateur RCNA366I40ZXBN<\/strong> mais \u00e9galement les m\u00eames fonctionnalit\u00e9s. Cependant, les panneaux de commande de r\u00e9glages des temp\u00e9ratures \u00e9lectroniques du r\u00e9frig\u00e9rateur se situent sur la fa\u00e7ade. <strong>Son prix est de 699 euros.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"le-refrigerateur-rcne560e40zxpn-3f66a4ed-206e-4f50-a2e8-bd7c9304d717\">Le r\u00e9frig\u00e9rateur RCNE560E40ZXPN<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le r\u00e9frig\u00e9rateur RCNE560E40ZX dispose quant \u00e0 lui de tous les avantages des deux pr\u00e9c\u00e9dents mod\u00e8les, <\/strong>mais sa capacit\u00e9 de stockage totale s\u2019\u00e9l\u00e8ve \u00e0 501 Litres dont 356 L pour la partie r\u00e9frig\u00e9ration, et 145 L pour la partie cong\u00e9lation. Ce r\u00e9frig\u00e9rateur Beko est plus large de 10 cm que les pr\u00e9c\u00e9dents mod\u00e8les qui sont large de 60 cm. De plus, il est aussi plus grand et mesure 192 cm contre 185 cm pour r\u00e9frig\u00e9rateur RCNA366I40ZXBN&nbsp; et 186 cm pour le r\u00e9frig\u00e9rateur RCNE366E40ZXBN. <strong>Son prix est de 799 euros.<\/strong><br>\u00c0 travers cette innovation, le fabricant de <a class=\"rank-math-link\" href=\"https:\/\/www.adepem.com\/refrigerateur\/m-beko\">r\u00e9frig\u00e9rateurs Beko<\/a> est soucieux d\u2019aider les consommateurs \u00e0 manger plus sainement et \u00e0 pr\u00e9server les vitamines des aliments le plus longtemps possible. Les futurs mod\u00e8les de r\u00e9frig\u00e9rateurs \u00e9quip\u00e9s de la technologie HarvestFresh\u00ae seront disponibles \u00e0 la vente \u00e0 partir de l\u2019ann\u00e9e prochaine.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fabricant Beko innove dans ses nouvelles gammes de r\u00e9frig\u00e9rateurs gr\u00e2ce \u00e0 la technologie HarvestFresh inspir\u00e9e par la nature. On vous explique tout. Beko est une des entreprises europ\u00e9ennes leaders dans l&rsquo;\u00e9lectrom\u00e9nager appartenant au groupe turc Ar\u00e7elike. Le fabricant vient de sortir sa nouvelle gamme de r\u00e9frig\u00e9rateurs en int\u00e9grant le syst\u00e8me HarvestFresh. Le HarvestFresh est une technologie inspir\u00e9e par la nature, permettant de simuler les changements de lumi\u00e8re dans votre r\u00e9frig\u00e9rateur tout au long de la journ\u00e9e. Cette technique a pour objectif d\u2019am\u00e9liorer la conservation des aliments. Ces nouveaux r\u00e9frig\u00e9rateurs sont compos\u00e9s d\u2019un ensemble de leds (bleues, vertes et rouges)&hellip;<\/p>\n","protected":false},"author":5,"featured_media":4485,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[481],"tags":[],"class_list":["post-4480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-electromenager"],"modified_by":"Quentin","author_meta":{"display_name":"Fred","author_link":"https:\/\/www.adepem.com\/blog\/auteur\/fred\/"},"featured_img":"https:\/\/www.adepem.com\/blog\/wp-content\/uploads\/2021\/02\/beko-refrigerateurs-technologie-harvestfresh-270x152.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.adepem.com\/blog\/actu-electromenager\/\" class=\"advgb-post-tax-term\">L\u2019actu \u00e9lectrom\u00e9nager<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">L\u2019actu \u00e9lectrom\u00e9nager<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 5 ans il y a","modified":"Mis \u00e0 jour 6 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 5 mars 2021","modified":"Mise \u00e0 jour le 2 mars 2021"},"absolute_dates_time":{"created":"Publi\u00e9 le 5 mars 2021 7 h 00 min","modified":"Mise \u00e0 jour le 2 mars 2021 17 h 19 min"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts\/4480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/comments?post=4480"}],"version-history":[{"count":3,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts\/4480\/revisions"}],"predecessor-version":[{"id":4504,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/posts\/4480\/revisions\/4504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/media\/4485"}],"wp:attachment":[{"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/media?parent=4480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/categories?post=4480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adepem.com\/blog\/wp-json\/wp\/v2\/tags?post=4480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}